{"id":114441,"date":"2025-05-06T01:30:08","date_gmt":"2025-05-06T00:30:08","guid":{"rendered":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/"},"modified":"2025-05-06T01:30:08","modified_gmt":"2025-05-06T00:30:08","slug":"boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia","status":"publish","type":"post","link":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/","title":{"rendered":"BOA 6\/05\/25 &#8211; ORDEN HAP\/433\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia."},"content":{"rendered":"<p>Contenido de la entrada<\/p>","protected":false},"excerpt":{"rendered":"<p>Contenido de la entrada<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[],"class_list":["post-114441","post","type-post","status-publish","format-standard","hentry","category-legislacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BOA 6\/05\/25 - ORDEN HAP\/433\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia. - bip4ex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BOA 6\/05\/25 - ORDEN HAP\/433\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia.\" \/>\n<meta property=\"og:description\" content=\"Contenido de la entrada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/\" \/>\n<meta property=\"og:site_name\" content=\"bip4ex\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T00:30:08+00:00\" \/>\n<meta name=\"author\" content=\"Luis Miguel Mej\u00edas Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Miguel Mej\u00edas Ramos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\\\/\"},\"author\":{\"name\":\"Luis Miguel Mej\u00edas Ramos\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#\\\/schema\\\/person\\\/3767b0619d59a11570372c821f8619ca\"},\"headline\":\"BOA 6\\\/05\\\/25 &#8211; ORDEN HAP\\\/433\\\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia.\",\"datePublished\":\"2025-05-06T00:30:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\\\/\"},\"wordCount\":31,\"publisher\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#organization\"},\"articleSection\":[\"Legislacion\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\\\/\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\\\/\",\"name\":\"BOA 6\\\/05\\\/25 - ORDEN HAP\\\/433\\\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia. - bip4ex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#website\"},\"datePublished\":\"2025-05-06T00:30:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BOA 6\\\/05\\\/25 &#8211; ORDEN HAP\\\/433\\\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#website\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/\",\"name\":\"bip4ex\",\"description\":\"Vigilancia Tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#organization\",\"name\":\"Helloproject.es\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bip4ex.png\",\"contentUrl\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bip4ex.png\",\"width\":322,\"height\":365,\"caption\":\"Helloproject.es\"},\"image\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#\\\/schema\\\/person\\\/3767b0619d59a11570372c821f8619ca\",\"name\":\"Luis Miguel Mej\u00edas Ramos\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/author\\\/luismi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BOA 6\/05\/25 - ORDEN HAP\/433\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia. - bip4ex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/","og_locale":"es_ES","og_type":"article","og_title":"BOA 6\/05\/25 - ORDEN HAP\/433\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia.","og_description":"Contenido de la entrada","og_url":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/","og_site_name":"bip4ex","article_published_time":"2025-05-06T00:30:08+00:00","author":"Luis Miguel Mej\u00edas Ramos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luis Miguel Mej\u00edas Ramos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/#article","isPartOf":{"@id":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/"},"author":{"name":"Luis Miguel Mej\u00edas Ramos","@id":"https:\/\/helloproject.es\/vigilancia\/#\/schema\/person\/3767b0619d59a11570372c821f8619ca"},"headline":"BOA 6\/05\/25 &#8211; ORDEN HAP\/433\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia.","datePublished":"2025-05-06T00:30:08+00:00","mainEntityOfPage":{"@id":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/"},"wordCount":31,"publisher":{"@id":"https:\/\/helloproject.es\/vigilancia\/#organization"},"articleSection":["Legislacion"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/","url":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/","name":"BOA 6\/05\/25 - ORDEN HAP\/433\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia. - bip4ex","isPartOf":{"@id":"https:\/\/helloproject.es\/vigilancia\/#website"},"datePublished":"2025-05-06T00:30:08+00:00","breadcrumb":{"@id":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/helloproject.es\/vigilancia\/boa-6-05-25-orden-hap-433-2025-de-21-de-abril-por-la-que-se-modifica-la-relacion-de-puestos-de-trabajo-del-departamento-de-presidencia-economia-y-justicia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/helloproject.es\/vigilancia\/"},{"@type":"ListItem","position":2,"name":"BOA 6\/05\/25 &#8211; ORDEN HAP\/433\/2025, de 21 de abril, por la que se modifica la Relaci\u00f3n de Puestos de Trabajo del Departamento de Presidencia, Econom\u00eda y Justicia."}]},{"@type":"WebSite","@id":"https:\/\/helloproject.es\/vigilancia\/#website","url":"https:\/\/helloproject.es\/vigilancia\/","name":"bip4ex","description":"Vigilancia Tecnol\u00f3gica","publisher":{"@id":"https:\/\/helloproject.es\/vigilancia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/helloproject.es\/vigilancia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/helloproject.es\/vigilancia\/#organization","name":"Helloproject.es","url":"https:\/\/helloproject.es\/vigilancia\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/helloproject.es\/vigilancia\/#\/schema\/logo\/image\/","url":"https:\/\/helloproject.es\/vigilancia\/wp-content\/uploads\/2023\/07\/bip4ex.png","contentUrl":"https:\/\/helloproject.es\/vigilancia\/wp-content\/uploads\/2023\/07\/bip4ex.png","width":322,"height":365,"caption":"Helloproject.es"},"image":{"@id":"https:\/\/helloproject.es\/vigilancia\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/helloproject.es\/vigilancia\/#\/schema\/person\/3767b0619d59a11570372c821f8619ca","name":"Luis Miguel Mej\u00edas Ramos","url":"https:\/\/helloproject.es\/vigilancia\/author\/luismi\/"}]}},"_links":{"self":[{"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/posts\/114441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/comments?post=114441"}],"version-history":[{"count":0,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/posts\/114441\/revisions"}],"wp:attachment":[{"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/media?parent=114441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/categories?post=114441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/tags?post=114441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}