{"id":74247,"date":"2025-03-06T15:23:32","date_gmt":"2025-03-06T14:23:32","guid":{"rendered":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/"},"modified":"2025-03-06T15:23:32","modified_gmt":"2025-03-06T14:23:32","slug":"las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada","status":"publish","type":"post","link":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/","title":{"rendered":"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada"},"content":{"rendered":"<p>El Ministerio de Ciencia, Innovaci\u00f3n y Universidades (MICIU) ha presentado hoy el informe <a href=\"https:\/\/www.ciencia.gob.es\/Secc-Servicios\/Igualdad\/CientificasCifras.html\" target=\"_blank\" title=\"Abre en ventana nueva\">\u2018Cient\u00edficas en Cifras 2025<\/a>, la octava edici\u00f3n de una serie de estudios que analizan la situaci\u00f3n de las mujeres en la I+D en Espa\u00f1a.<\/p>\n<p>El objetivo de este estudio es proporcionar un diagn\u00f3stico actualizado de la igualdad de g\u00e9nero en la ciencia, identificando avances y brechas, as\u00ed como formular recomendaciones para fortalecer la equidad en el sistema de investigaci\u00f3n e innovaci\u00f3n.<\/p>\n<p>El informe destaca, entre otros datos, que la representaci\u00f3n femenina en la Administraci\u00f3n P\u00fablica ha alcanzado la paridad con un 50,5 % de investigadoras, lo que supone un avance notable en este sector frente al 31,2 % del sector empresarial privado. Es decir, una presencia de mujeres baja. Como consecuencia de estos datos, la media de investigadoras en Espa\u00f1a se sit\u00faa en el 39,6 %, apenas un punto porcentual por encima de los datos de 2014.<\/p>\n<p>La media de investigadoras en Espa\u00f1a se sit\u00faa en el 39,6 %, apenas un punto porcentual por encima de los datos de 2014, debido a la menor apuesta del sector empresarial<\/p>\n<p><a><\/a><\/p>\n<h2>Universidad p\u00fablica<\/h2>\n<p>Por otro lado, el informe tambi\u00e9n concluye que que la integraci\u00f3n de la perspectiva de g\u00e9nero en la investigaci\u00f3n alcanza un 79,5 % en las universidades p\u00fablicas frente al 4 % en las privadas.<\/p>\n<p>Adem\u00e1s, las pol\u00edticas de prevenci\u00f3n y actuaci\u00f3n frente al acoso sexual y por raz\u00f3n de sexo, as\u00ed como las pol\u00edticas de conciliaci\u00f3n de la vida personal, laboral y familiar como instrumentos al servicio de la igualdad, se han implementado de forma generalizada en las universidades y en los\u00a0Organismos P\u00fablicos de Investigaci\u00f3n (OPIs).<\/p>\n<p>El techo de cristal para acceder a los puestos m\u00e1s altos de la carrera investigadora se reduce significativamente en los \u00faltimos 5 a\u00f1os<\/p>\n<p>Otro de los datos que arroja el informe es que el \u00edndice de techo de cristal, que mide la dificultad de las mujeres para acceder a los puestos m\u00e1s altos de la carrera investigadora, se ha reducido significativamente en los \u00faltimos 5 a\u00f1os (pasando de 1,73 en el curso 2018-2019 a 1,57 en 2022-2023) por lo que si se mantienen los ritmos de descenso actuales, las mujeres alcanzar\u00edan la misma representaci\u00f3n que los hombres en los niveles m\u00e1s altos de la carrera investigadora en un promedio de 15 a\u00f1os.<\/p>\n<p>La representaci\u00f3n de mujeres en puestos de liderazgo ha mejorado: el porcentaje de rectoras ha pasado del 22 % en 2018 al 27 %<\/p>\n<p>Actualmente, la representaci\u00f3n de mujeres en puestos de liderazgo ha mejorado y un ejemplo de ello es que el porcentaje de rectoras ha pasado del 22 % en 2018 al 27 %.<\/p>\n<p>En el curso 2022-2023, el porcentaje de catedr\u00e1ticas es del 27% frente al 20% de 2012-2013 y las profesoras de investigaci\u00f3n en Organismos P\u00fablicos de Investigaci\u00f3n (OPIs) representan el 26,6% frente al 23,9%, en el mismo periodo de tiempo.<\/p>\n<p>Participaci\u00f3n en estudios superiores<\/p>\n<p>En los \u00faltimos a\u00f1os, la participaci\u00f3n femenina en estudios superiores ha experimentado tambi\u00e9n un incremento significativo. En Grado, el porcentaje de mujeres ha pasado del 54, 2% en 2014-2015 al 57 % en 2023-2024. En M\u00e1ster, ha crecido del 53,3 % al 56,4 %, y en Doctorado ha superado el umbral del 50 % (del 49,6 % al 50,2 %). Sin embargo, este avance no se refleja de manera equitativa en todas las disciplinas.<\/p>\n<p>Desde el curso 2018-19 se aprecia un cambio de tendencia en ingenier\u00eda y arquitectura, el \u00e1rea m\u00e1s masculinizada, en todos los niveles de estudios (en grado ha pasado del 25,0 % en el curso 2017-18 al 28,1 % de 2023-24, en m\u00e1ster del 28,6 % al 31,2 % y en doctorado del 29,5 % al 31,1 %).<\/p>\n<p><a><\/a><\/p>\n<h2>Impactos de la Ley de la Ciencia de 2022<\/h2>\n<p>El informe tambi\u00e9n analiza los impactos de la Ley de la Ciencia de 2022 y otras normativas recientes en la igualdad de g\u00e9nero dentro del sector. En este sentido, el informe destaca que, desde la aplicaci\u00f3n de la Ley, la participaci\u00f3n de mujeres en comisiones de evaluaci\u00f3n ha crecido del 42,7 % en 2020 al 44,5 % en 2023, garantizando una mayor equidad en la asignaci\u00f3n de recursos.<\/p>\n<p>Una de las novedades de esta edici\u00f3n es un estudio de percepciones a trav\u00e9s de encuestas y grupos focales, permitiendo complementar el an\u00e1lisis cuantitativo con la experiencia directa del personal investigador. El informe manifiesta la persistencia de las\u00a0barreras estructurales a las que las mujeres se enfrentan en su carrera profesional y la existencia de puntos de vista contrapuestos entre las vivencias de mujeres y hombres.<\/p>\n<p>Las mujeres valoran considerablemente peor que los hombres las medidas de conciliaci\u00f3n entre la vida laboral y personal<\/p>\n<p>Por ejemplo, las mujeres valoran considerablemente peor que los hombres las medidas de conciliaci\u00f3n entre la vida laboral y personal, y perciben m\u00e1s dificultades que ellos en el acceso a oportunidades en condici\u00f3n de igualdad de m\u00e9ritos.<\/p>\n<p>Adem\u00e1s, el acoso sexual y por raz\u00f3n de sexo aparece como un problema que afecta mayoritariamente a las mujeres y al que los hombres son menos sensibles y del que son menos conscientes.<\/p>\n<p><a><\/a><\/p>\n<h2>Metodolog\u00eda<\/h2>\n<p>El documento se ha realizado a trav\u00e9s de encuestas con la participaci\u00f3n de 2465 personas del sector de la investigaci\u00f3n con el fin de conocer su percepci\u00f3n sobre la equidad de g\u00e9nero en sus centros de trabajo.<\/p>\n<p>Adicionalmente, se han desarrollado 7 grupos focales, en los que han participado m\u00e1s de 41 investigadoras e investigadores pertenecientes a diferentes instituciones acad\u00e9micas y organismos de investigaci\u00f3n. Estas sesiones permitieron identificar barreras espec\u00edficas, buenas pr\u00e1cticas y propuestas de mejora.<\/p>\n<p>La secretaria general de Investigaci\u00f3n del MICIU,\u00a0Eva Ortega Pa\u00edno, ha clausurado el acto de presentaci\u00f3n del informe, en el que tambi\u00e9n han intervenido la directora de la Unidad de Mujeres y Ciencia del MICIU,\u00a0Silvia Rueda Pascual, y la directora general de la Fundaci\u00f3n Espa\u00f1ola para la Ciencia y la Tecnolog\u00eda,\u00a0Izaskun Lacunza Aguirrebengoa, que colabora en la elaboraci\u00f3n del informe.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Ciencia, Innovaci\u00f3n y Universidades (MICIU) ha presentado hoy el informe \u2018Cient\u00edficas en Cifras 2025, la octava edici\u00f3n de una serie de estudios que analizan la situaci\u00f3n de las mujeres en la I+D en Espa\u00f1a. El objetivo de este estudio es proporcionar un diagn\u00f3stico actualizado de la igualdad de g\u00e9nero en la ciencia, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[],"class_list":["post-74247","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada - bip4ex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Ciencia, Innovaci\u00f3n y Universidades (MICIU) ha presentado hoy el informe \u2018Cient\u00edficas en Cifras 2025, la octava edici\u00f3n de una serie de estudios que analizan la situaci\u00f3n de las mujeres en la I+D en Espa\u00f1a. El objetivo de este estudio es proporcionar un diagn\u00f3stico actualizado de la igualdad de g\u00e9nero en la ciencia, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/\" \/>\n<meta property=\"og:site_name\" content=\"bip4ex\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-06T14:23:32+00:00\" \/>\n<meta name=\"author\" content=\"Luis Miguel Mej\u00edas Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Miguel Mej\u00edas Ramos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\\\/\"},\"author\":{\"name\":\"Luis Miguel Mej\u00edas Ramos\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#\\\/schema\\\/person\\\/3767b0619d59a11570372c821f8619ca\"},\"headline\":\"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada\",\"datePublished\":\"2025-03-06T14:23:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\\\/\"},\"wordCount\":1017,\"publisher\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\\\/\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\\\/\",\"name\":\"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada - bip4ex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#website\"},\"datePublished\":\"2025-03-06T14:23:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#website\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/\",\"name\":\"bip4ex\",\"description\":\"Vigilancia Tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#organization\",\"name\":\"Helloproject.es\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bip4ex.png\",\"contentUrl\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bip4ex.png\",\"width\":322,\"height\":365,\"caption\":\"Helloproject.es\"},\"image\":{\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/#\\\/schema\\\/person\\\/3767b0619d59a11570372c821f8619ca\",\"name\":\"Luis Miguel Mej\u00edas Ramos\",\"url\":\"https:\\\/\\\/helloproject.es\\\/vigilancia\\\/author\\\/luismi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada - bip4ex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/","og_locale":"es_ES","og_type":"article","og_title":"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada","og_description":"El Ministerio de Ciencia, Innovaci\u00f3n y Universidades (MICIU) ha presentado hoy el informe \u2018Cient\u00edficas en Cifras 2025, la octava edici\u00f3n de una serie de estudios que analizan la situaci\u00f3n de las mujeres en la I+D en Espa\u00f1a. El objetivo de este estudio es proporcionar un diagn\u00f3stico actualizado de la igualdad de g\u00e9nero en la ciencia, [&hellip;]","og_url":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/","og_site_name":"bip4ex","article_published_time":"2025-03-06T14:23:32+00:00","author":"Luis Miguel Mej\u00edas Ramos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luis Miguel Mej\u00edas Ramos","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/#article","isPartOf":{"@id":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/"},"author":{"name":"Luis Miguel Mej\u00edas Ramos","@id":"https:\/\/helloproject.es\/vigilancia\/#\/schema\/person\/3767b0619d59a11570372c821f8619ca"},"headline":"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada","datePublished":"2025-03-06T14:23:32+00:00","mainEntityOfPage":{"@id":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/"},"wordCount":1017,"publisher":{"@id":"https:\/\/helloproject.es\/vigilancia\/#organization"},"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/","url":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/","name":"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada - bip4ex","isPartOf":{"@id":"https:\/\/helloproject.es\/vigilancia\/#website"},"datePublished":"2025-03-06T14:23:32+00:00","breadcrumb":{"@id":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/helloproject.es\/vigilancia\/las-investigadoras-son-ya-el-505-en-la-administracion-publica-frente-al-312-en-la-empresa-privada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/helloproject.es\/vigilancia\/"},{"@type":"ListItem","position":2,"name":"Las investigadoras son ya el 50,5 % en la Administraci\u00f3n P\u00fablica frente al 31,2 % en la empresa privada"}]},{"@type":"WebSite","@id":"https:\/\/helloproject.es\/vigilancia\/#website","url":"https:\/\/helloproject.es\/vigilancia\/","name":"bip4ex","description":"Vigilancia Tecnol\u00f3gica","publisher":{"@id":"https:\/\/helloproject.es\/vigilancia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/helloproject.es\/vigilancia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/helloproject.es\/vigilancia\/#organization","name":"Helloproject.es","url":"https:\/\/helloproject.es\/vigilancia\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/helloproject.es\/vigilancia\/#\/schema\/logo\/image\/","url":"https:\/\/helloproject.es\/vigilancia\/wp-content\/uploads\/2023\/07\/bip4ex.png","contentUrl":"https:\/\/helloproject.es\/vigilancia\/wp-content\/uploads\/2023\/07\/bip4ex.png","width":322,"height":365,"caption":"Helloproject.es"},"image":{"@id":"https:\/\/helloproject.es\/vigilancia\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/helloproject.es\/vigilancia\/#\/schema\/person\/3767b0619d59a11570372c821f8619ca","name":"Luis Miguel Mej\u00edas Ramos","url":"https:\/\/helloproject.es\/vigilancia\/author\/luismi\/"}]}},"_links":{"self":[{"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/posts\/74247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/comments?post=74247"}],"version-history":[{"count":0,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/posts\/74247\/revisions"}],"wp:attachment":[{"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/media?parent=74247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/categories?post=74247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/helloproject.es\/vigilancia\/wp-json\/wp\/v2\/tags?post=74247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}